{"id":1680,"date":"2024-08-27T17:14:21","date_gmt":"2024-08-27T15:14:21","guid":{"rendered":"https:\/\/www.prolococastellanagrotte.it\/?page_id=1680"},"modified":"2024-10-26T19:55:03","modified_gmt":"2024-10-26T17:55:03","slug":"badessa-la-forza-e-femmina","status":"publish","type":"page","link":"https:\/\/www.prolococastellanagrotte.it\/es\/badessa-la-forza-e-femmina\/","title":{"rendered":"39 &#8211; Badessa &#8211; La forza (\u00e8 femmina)"},"content":{"rendered":"<div class=\"vc_row wpb_row vc_row-fluid gino\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: center;\"><span style=\"font-size: 18pt;\"><strong><span style=\"color: #ff6d09;\"><a href=\"\/es\/mappa-completa-le-porte-della-badessa\/#mappacompleta\"><span style=\"font-size: 14pt;\">Visualizza la mappa interattiva completa delle porte della Badessa<\/span><\/a><br \/>\n<a href=\"\/es\/mappa-completa-le-porte-della-badessa\/#mappacompleta\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-299\" src=\"http:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2021\/11\/maps-icon-16-300x300.png\" alt=\"\" width=\"77\" height=\"77\" srcset=\"https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2021\/11\/maps-icon-16-300x300.png 300w, https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2021\/11\/maps-icon-16-150x150.png 150w, https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2021\/11\/maps-icon-16-100x100.png 100w, https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2021\/11\/maps-icon-16.png 320w\" sizes=\"auto, (max-width: 77px) 100vw, 77px\" \/><\/a><\/span><\/strong><\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_row wpb_row vc_inner vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_left\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" width=\"606\" height=\"573\" src=\"https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2024\/10\/artista-5.jpg\" class=\"vc_single_image-img attachment-full\" alt=\"\" srcset=\"https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2024\/10\/artista-5.jpg 606w, https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2024\/10\/artista-5-300x284.jpg 300w, https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2024\/10\/artista-5-13x12.jpg 13w\" sizes=\"auto, (max-width: 606px) 100vw, 606px\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-8\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Immaginate, siamo nel 1266. Per la prima volta nella storia della chiesa cattolica, una donna, Dameta, ottiene i poteri vescovili. A lei seguiranno innumerevoli altre donne, le cosiddette badesse, figure potenti, intransigenti, custodi e detentrici del potere spirituale e temporale su questo paese e dintorni. La loro storia, durata quasi seicento anni, segn\u00f2 il nostro territorio nonostante le controversie. Da allora sono passati secoli, anni di oblio. Tocca dunque a noi ricordare e omaggiare queste donne che prima della diffusione e nascita del femminismo, sono state esempi del potere femminile in un contesto che ha sempre relegato la figura della donna ad uno spazio bidimensionale e limitato. La badessa, sostantivo femminile, \u00e8 un emblema di potere, un potere che ormai risiede nella memoria, ma che non per questo debba esser sminuito. Dopotutto, anche la memoria, cos\u00ec come la forza, somo anch&#8217;essi sostantivi femminili.<br \/>\n<\/span><\/p>\n<p style=\"text-align: right;\"><span style=\"font-size: 14pt;\"><br \/>\n<strong>Ga-Lia<\/strong><\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: center;\"><span style=\"font-size: 13pt;\"><strong>\u00bfTienes una puerta en el camino que quieres nominar? <a href=\"mailto:prolococastellanagrotte@gmail.com?subject=Porta%20da%20candidare%20per%20le%20Badesse\">haga clic aqu\u00ed<\/a><\/strong><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 13pt;\"><strong>\u00bfT\u00fa tambi\u00e9n quieres participar en la pr\u00f3xima edici\u00f3n? <a href=\"mailto:prolococastellanagrotte@gmail.com?subject=Voglio%20partecipare%20alla%20prossima%20edizione%20delle%20Badesse\">haga clic aqu\u00ed<\/a><\/strong><\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid gino\"><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_left\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<a class=\"\" data-lightbox=\"lightbox[rel-1680-311057193]\" href=\"https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2024\/10\/bozzetto-la-forza-723x1024.jpeg\" target=\"_self\"><img loading=\"lazy\" decoding=\"async\" width=\"1809\" height=\"2560\" src=\"https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2024\/10\/bozzetto-la-forza-scaled.jpeg\" class=\"vc_single_image-img attachment-full\" alt=\"\" srcset=\"https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2024\/10\/bozzetto-la-forza-scaled.jpeg 1809w, https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2024\/10\/bozzetto-la-forza-212x300.jpeg 212w, https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2024\/10\/bozzetto-la-forza-723x1024.jpeg 723w, https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2024\/10\/bozzetto-la-forza-768x1087.jpeg 768w, https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2024\/10\/bozzetto-la-forza-1085x1536.jpeg 1085w, https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2024\/10\/bozzetto-la-forza-1447x2048.jpeg 1447w, https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2024\/10\/bozzetto-la-forza-8x12.jpeg 8w\" sizes=\"auto, (max-width: 1809px) 100vw, 1809px\" \/><\/a>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<a class=\"\" data-lightbox=\"lightbox[rel-1680-181902245]\" href=\"https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2024\/10\/prima-la-forza.jpeg\" target=\"_self\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2024\/10\/prima-la-forza.jpeg\" class=\"vc_single_image-img attachment-full\" alt=\"\" srcset=\"https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2024\/10\/prima-la-forza.jpeg 768w, https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2024\/10\/prima-la-forza-225x300.jpeg 225w, https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2024\/10\/prima-la-forza-9x12.jpeg 9w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<a class=\"\" data-lightbox=\"lightbox[rel-1680-2140955590]\" href=\"https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2024\/10\/1726606309979-682x1024.jpg\" target=\"_self\"><img loading=\"lazy\" decoding=\"async\" width=\"1066\" height=\"1600\" src=\"https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2024\/10\/1726606309979.jpg\" class=\"vc_single_image-img attachment-full\" alt=\"\" srcset=\"https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2024\/10\/1726606309979.jpg 1066w, https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2024\/10\/1726606309979-200x300.jpg 200w, https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2024\/10\/1726606309979-682x1024.jpg 682w, https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2024\/10\/1726606309979-768x1153.jpg 768w, https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2024\/10\/1726606309979-1023x1536.jpg 1023w, https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2024\/10\/1726606309979-8x12.jpg 8w\" sizes=\"auto, (max-width: 1066px) 100vw, 1066px\" \/><\/a>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid gino\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: center;\"><span style=\"font-size: 18pt;\"><strong>Dove si trova e come raggiungerla (Riferimento n.39)<\/strong><\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid gino\"><div class=\"ciccio wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_left\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" data-vc-zoom=\"https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2024\/10\/mappa-669x1024.jpg\" width=\"1045\" height=\"1600\" src=\"https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2024\/10\/mappa.jpg\" class=\"vc_single_image-img attachment-full\" alt=\"\" srcset=\"https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2024\/10\/mappa.jpg 1045w, https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2024\/10\/mappa-196x300.jpg 196w, https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2024\/10\/mappa-669x1024.jpg 669w, https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2024\/10\/mappa-768x1176.jpg 768w, https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2024\/10\/mappa-1003x1536.jpg 1003w, https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2024\/10\/mappa-8x12.jpg 8w\" sizes=\"auto, (max-width: 1045px) 100vw, 1045px\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_raw_code wpb_content_element wpb_raw_html\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n            <div \n                class=\"elfsight-widget-google-maps elfsight-widget\" \n                data-elfsight-google-maps-options=\"%7B%22categoriesEnabled%22%3Afalse%2C%22categories%22%3A%5B%5D%2C%22icons%22%3A%5B%7B%22value%22%3A%22%22%2C%22name%22%3A%22%20-%20None%20-%20%22%2C%22visible%22%3Afalse%7D%2C%7B%22value%22%3A%229361a380-1e92-4303-8aa2-7e8c2c073469%22%2C%22name%22%3A%22star%22%2C%22preview%22%3A%22https%3A%5C%2F%5C%2Fassets-elfsight-com.sfo2.digitaloceanspaces.com%5C%2Fapps%5C%2Fgoogle-maps%5C%2Fmarkers%5C%2Fmarker-star.svg%22%2C%22iconType%22%3A%22library%22%2C%22iconLibrary%22%3A%22star%22%2C%22iconCustom%22%3Anull%2C%22iconColor%22%3A%22%22%2C%22iconSize%22%3A32%7D%5D%2C%22lang%22%3A%22it%22%2C%22distanceUnits%22%3A%22km%22%2C%22markers%22%3A%5B%7B%22position%22%3A%2240.885603007724214%2C%2017.16990041292225%22%2C%22coordinates%22%3A%2240.885603007724214%2C%2017.16990041292225%22%2C%22infoTitle%22%3A%2239%20-%20Badessa%20-%20La%20forza%20%28%5Cu00e8%20femmina%29%22%2C%22category%22%3A%22%22%2C%22icon%22%3A%22%22%2C%22infoDescription%22%3A%22%22%2C%22infoImage%22%3A%22https%3A%5C%2F%5C%2Fwww.prolococastellanagrotte.it%5C%2Fwp-content%5C%2Fuploads%5C%2F2024%5C%2F10%5C%2F1726606309979.jpg%22%2C%22infoAddress%22%3A%22Vico%20Giammarino%2C%2024%22%2C%22infoSite%22%3A%22%22%2C%22infoPhone%22%3A%22%22%2C%22infoEmail%22%3A%22%22%2C%22infoWorkingHours%22%3A%22%22%2C%22markerClickAction%22%3A%22infoWindow%22%2C%22infoWindowOpenedByDefault%22%3Afalse%2C%22linkUrl%22%3A%22%22%2C%22animation%22%3A%22none%22%7D%5D%2C%22mapType%22%3A%22roadmap%22%2C%22center%22%3A%22auto%22%2C%22zoom%22%3A%22auto%22%2C%22controls%22%3A%5B%22zoom%22%2C%22mapType%22%2C%22scale%22%2C%22streetView%22%2C%22rotate%22%2C%22fullScreen%22%5D%2C%22markerClusterEnabled%22%3Atrue%2C%22markerClusterZoom%22%3Atrue%2C%22markerClusterMin%22%3A2%2C%22markerClusterIcon%22%3A%22default%22%2C%22markerClusterIconColor%22%3A%22%22%2C%22markerClusterIconUrl%22%3Anull%2C%22markerClusterSize%22%3A52%2C%22infoDirections%22%3Atrue%2C%22directionsTarget%22%3A%22google%22%2C%22scrollwheel%22%3Afalse%2C%22draggable%22%3Atrue%2C%22layers%22%3A%5B%5D%2C%22width%22%3A%22auto%22%2C%22height%22%3A%22850%22%2C%22panelEnabled%22%3Afalse%2C%22panelOpenByDefault%22%3Atrue%2C%22panelSearchVisible%22%3Atrue%2C%22panelSearchBy%22%3A%22markers%22%2C%22panelSearchPlaceholder%22%3A%22%22%2C%22panelListItemElements%22%3A%5B%22title%22%2C%22category%22%2C%22image%22%2C%22address%22%2C%22phone%22%2C%22workingHours%22%5D%2C%22mainColor%22%3A%22rgb%2866%2C%20133%2C%20244%29%22%2C%22style%22%3A%22custom%22%2C%22colorGeometry%22%3A%22rgb%28235%2C%20227%2C%20205%29%22%2C%22colorLabelsTextFill%22%3A%22rgb%2882%2C%2055%2C%2053%29%22%2C%22colorLabelsTextStroke%22%3A%22rgba%28245%2C241%2C230%2C1%29%22%2C%22colorAdministrativeGeometryStroke%22%3A%22rgba%28201%2C178%2C166%2C1%29%22%2C%22colorAdministrativeLandParcel%22%3A%22rgba%28174%2C158%2C144%2C1%29%22%2C%22colorLandscapeNaturalGeometry%22%3A%22rgba%28223%2C210%2C174%2C1%29%22%2C%22colorPoiGeometry%22%3A%22rgba%28223%2C210%2C174%2C1%29%22%2C%22colorPoiLabelsTextFill%22%3A%22rgba%28147%2C129%2C124%2C1%29%22%2C%22colorPoiParkGeometryFill%22%3A%22rgba%28165%2C176%2C118%2C1%29%22%2C%22colorPoiParkLabelsTextFill%22%3A%22rgba%2868%2C117%2C48%2C1%29%22%2C%22colorRoadGeometry%22%3A%22rgba%28245%2C241%2C230%2C1%29%22%2C%22colorRoadArterial%22%3A%22rgba%28253%2C252%2C248%2C1%29%22%2C%22colorRoadHighway%22%3A%22rgba%28248%2C201%2C103%2C1%29%22%2C%22colorRoadHighwayGeometryStroke%22%3A%22rgba%28233%2C188%2C98%2C1%29%22%2C%22colorRoadHighwayControlledAccessGeometry%22%3A%22rgba%28233%2C141%2C88%2C1%29%22%2C%22colorRoadHighwayControlledAccessGeometryStroke%22%3A%22rgba%28219%2C133%2C85%2C1%29%22%2C%22colorRoadLocalLabelsTextFill%22%3A%22rgba%28128%2C107%2C99%2C1%29%22%2C%22colorTransitLineGeometry%22%3A%22rgba%28223%2C210%2C174%2C1%29%22%2C%22colorTransitLineLabelsTextFill%22%3A%22rgba%28143%2C125%2C119%2C1%29%22%2C%22colorTransitLineLabelsTextStroke%22%3A%22rgba%28235%2C227%2C205%2C1%29%22%2C%22colorTransitStationGeometry%22%3A%22rgba%28223%2C210%2C174%2C1%29%22%2C%22colorWaterGeometryFill%22%3A%22rgba%28185%2C211%2C194%2C1%29%22%2C%22colorWaterLabelTextFill%22%3A%22rgba%28146%2C153%2C141%2C1%29%22%2C%22customGoogleMapsStyles%22%3A%22%22%2C%22apiKey%22%3A%22AIzaSyDuLxATglMSkmUM8pYqCfJkrn1X-mOmHTo%22%2C%22widgetId%22%3A%2274%22%7D\" \n                data-elfsight-google-maps-version=\"2.4.2\"\n                data-elfsight-widget-id=\"elfsight-google-maps-74\">\n            <\/div>\n            \n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"Visualizza la mappa interattiva completa delle porte della Badessa Immaginate, siamo nel 1266. Per la prima volta nella storia della chiesa cattolica, una donna, Dameta, ottiene i poteri vescovili. A lei seguiranno innumerevoli altre donne, le cosiddette badesse, figure potenti, intransigenti, custodi e detentrici del potere spirituale e temporale su<div class=\"re-read-more\"><a class=\"read-more\" href=\"https:\/\/www.prolococastellanagrotte.it\/es\/badessa-la-forza-e-femmina\/\">Leer m\u00e1s...<\/a><\/div>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"full-width.php","meta":{"footnotes":""},"class_list":["post-1680","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>39 - Badessa - La forza (\u00e8 femmina) - Pro Loco Castellana Grotte | Don Nicola Pellegrino<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.prolococastellanagrotte.it\/es\/badessa-la-forza-e-femmina\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"39 - Badessa - La forza (\u00e8 femmina) - Pro Loco Castellana Grotte | Don Nicola Pellegrino\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.prolococastellanagrotte.it\/es\/badessa-la-forza-e-femmina\/\" \/>\n<meta property=\"og:site_name\" content=\"Pro Loco Castellana Grotte | Don Nicola Pellegrino\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-26T17:55:03+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2021\/11\/maps-icon-16-300x300.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.prolococastellanagrotte.it\\\/badessa-la-forza-e-femmina\\\/\",\"url\":\"https:\\\/\\\/www.prolococastellanagrotte.it\\\/badessa-la-forza-e-femmina\\\/\",\"name\":\"39 - Badessa - La forza (\u00e8 femmina) - Pro Loco Castellana Grotte | Don Nicola Pellegrino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.prolococastellanagrotte.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.prolococastellanagrotte.it\\\/badessa-la-forza-e-femmina\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.prolococastellanagrotte.it\\\/badessa-la-forza-e-femmina\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.prolococastellanagrotte.it\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/maps-icon-16-300x300.png\",\"datePublished\":\"2024-08-27T15:14:21+00:00\",\"dateModified\":\"2024-10-26T17:55:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.prolococastellanagrotte.it\\\/badessa-la-forza-e-femmina\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.prolococastellanagrotte.it\\\/badessa-la-forza-e-femmina\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.prolococastellanagrotte.it\\\/badessa-la-forza-e-femmina\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.prolococastellanagrotte.it\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/maps-icon-16-300x300.png\",\"contentUrl\":\"http:\\\/\\\/www.prolococastellanagrotte.it\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/maps-icon-16-300x300.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.prolococastellanagrotte.it\\\/badessa-la-forza-e-femmina\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.prolococastellanagrotte.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"39 &#8211; Badessa &#8211; La forza (\u00e8 femmina)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.prolococastellanagrotte.it\\\/#website\",\"url\":\"https:\\\/\\\/www.prolococastellanagrotte.it\\\/\",\"name\":\"Pro Loco Castellana Grotte | Don Nicola Pellegrino\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.prolococastellanagrotte.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.prolococastellanagrotte.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.prolococastellanagrotte.it\\\/#organization\",\"name\":\"Pro Loco Castellana Grotte | Don Nicola Pellegrino\",\"url\":\"https:\\\/\\\/www.prolococastellanagrotte.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.prolococastellanagrotte.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.prolococastellanagrotte.it\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/cropped-logos_definitivo.png\",\"contentUrl\":\"https:\\\/\\\/www.prolococastellanagrotte.it\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/cropped-logos_definitivo.png\",\"width\":300,\"height\":157,\"caption\":\"Pro Loco Castellana Grotte | Don Nicola Pellegrino\"},\"image\":{\"@id\":\"https:\\\/\\\/www.prolococastellanagrotte.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"39 - Badessa - La forza (\u00e8 femmina) - Pro Loco Castellana Grotte | Don Nicola Pellegrino","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.prolococastellanagrotte.it\/es\/badessa-la-forza-e-femmina\/","og_locale":"es_ES","og_type":"article","og_title":"39 - Badessa - La forza (\u00e8 femmina) - Pro Loco Castellana Grotte | Don Nicola Pellegrino","og_url":"https:\/\/www.prolococastellanagrotte.it\/es\/badessa-la-forza-e-femmina\/","og_site_name":"Pro Loco Castellana Grotte | Don Nicola Pellegrino","article_modified_time":"2024-10-26T17:55:03+00:00","og_image":[{"url":"http:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2021\/11\/maps-icon-16-300x300.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.prolococastellanagrotte.it\/badessa-la-forza-e-femmina\/","url":"https:\/\/www.prolococastellanagrotte.it\/badessa-la-forza-e-femmina\/","name":"39 - Badessa - La forza (\u00e8 femmina) - Pro Loco Castellana Grotte | Don Nicola Pellegrino","isPartOf":{"@id":"https:\/\/www.prolococastellanagrotte.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.prolococastellanagrotte.it\/badessa-la-forza-e-femmina\/#primaryimage"},"image":{"@id":"https:\/\/www.prolococastellanagrotte.it\/badessa-la-forza-e-femmina\/#primaryimage"},"thumbnailUrl":"http:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2021\/11\/maps-icon-16-300x300.png","datePublished":"2024-08-27T15:14:21+00:00","dateModified":"2024-10-26T17:55:03+00:00","breadcrumb":{"@id":"https:\/\/www.prolococastellanagrotte.it\/badessa-la-forza-e-femmina\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.prolococastellanagrotte.it\/badessa-la-forza-e-femmina\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.prolococastellanagrotte.it\/badessa-la-forza-e-femmina\/#primaryimage","url":"http:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2021\/11\/maps-icon-16-300x300.png","contentUrl":"http:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2021\/11\/maps-icon-16-300x300.png"},{"@type":"BreadcrumbList","@id":"https:\/\/www.prolococastellanagrotte.it\/badessa-la-forza-e-femmina\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.prolococastellanagrotte.it\/"},{"@type":"ListItem","position":2,"name":"39 &#8211; Badessa &#8211; La forza (\u00e8 femmina)"}]},{"@type":"WebSite","@id":"https:\/\/www.prolococastellanagrotte.it\/#website","url":"https:\/\/www.prolococastellanagrotte.it\/","name":"Pro Loco Castellana Grotte | Don Nicola Pellegrino","description":"","publisher":{"@id":"https:\/\/www.prolococastellanagrotte.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.prolococastellanagrotte.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.prolococastellanagrotte.it\/#organization","name":"Pro Loco Castellana Grotte | Don Nicola Pellegrino","url":"https:\/\/www.prolococastellanagrotte.it\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.prolococastellanagrotte.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2021\/11\/cropped-logos_definitivo.png","contentUrl":"https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2021\/11\/cropped-logos_definitivo.png","width":300,"height":157,"caption":"Pro Loco Castellana Grotte | Don Nicola Pellegrino"},"image":{"@id":"https:\/\/www.prolococastellanagrotte.it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.prolococastellanagrotte.it\/es\/wp-json\/wp\/v2\/pages\/1680","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.prolococastellanagrotte.it\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.prolococastellanagrotte.it\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.prolococastellanagrotte.it\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.prolococastellanagrotte.it\/es\/wp-json\/wp\/v2\/comments?post=1680"}],"version-history":[{"count":8,"href":"https:\/\/www.prolococastellanagrotte.it\/es\/wp-json\/wp\/v2\/pages\/1680\/revisions"}],"predecessor-version":[{"id":1956,"href":"https:\/\/www.prolococastellanagrotte.it\/es\/wp-json\/wp\/v2\/pages\/1680\/revisions\/1956"}],"wp:attachment":[{"href":"https:\/\/www.prolococastellanagrotte.it\/es\/wp-json\/wp\/v2\/media?parent=1680"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}