{"id":734,"date":"2022-09-19T13:53:58","date_gmt":"2022-09-19T11:53:58","guid":{"rendered":"https:\/\/www.prolococastellanagrotte.it\/?page_id=734"},"modified":"2024-10-30T11:09:34","modified_gmt":"2024-10-30T10:09:34","slug":"9-pastorale-optical-mario-lozito","status":"publish","type":"page","link":"https:\/\/www.prolococastellanagrotte.it\/en\/9-pastorale-optical-mario-lozito\/","title":{"rendered":"25 &#8211; Badessa &#8211; Pastorale optical"},"content":{"rendered":"<div class=\"vc_row wpb_row vc_row-fluid gino\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: center;\"><span style=\"font-size: 18pt;\"><strong><span style=\"color: #ff6d09;\"><a href=\"\/en\/mappa-completa-le-porte-della-badessa\/#mappacompleta\"><span style=\"font-size: 14pt;\">Visualizza la mappa interattiva completa delle porte della Badessa<\/span><\/a><br \/>\n<a href=\"\/en\/mappa-completa-le-porte-della-badessa\/#mappacompleta\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-299\" src=\"http:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2021\/11\/maps-icon-16-300x300.png\" alt=\"\" width=\"77\" height=\"77\" srcset=\"https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2021\/11\/maps-icon-16-300x300.png 300w, https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2021\/11\/maps-icon-16-150x150.png 150w, https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2021\/11\/maps-icon-16-100x100.png 100w, https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2021\/11\/maps-icon-16.png 320w\" sizes=\"auto, (max-width: 77px) 100vw, 77px\" \/><\/a><\/span><\/strong><\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_row wpb_row vc_inner vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_images_carousel wpb_content_element vc_clearfix\"><div class=\"wpb_wrapper\"><div id=\"vc_images-carousel-1-1778641557\" data-ride=\"vc_carousel\" data-wrap=\"true\" style=\"width: 100%;\" data-interval=\"5000\" data-auto-height=\"yes\" data-mode=\"horizontal\" data-partial=\"false\" data-per-view=\"1\" data-hide-on-end=\"false\" class=\"vc_slide vc_images_carousel\"><div class=\"vc_carousel-inner\"><div class=\"vc_carousel-slideline\"><div class=\"vc_carousel-slideline-inner\"><div class=\"vc_item\"><div class=\"vc_inner\"><a class=\"\" href=\"https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2022\/09\/06-mario-lozito-3.jpg\" data-lightbox=\"lightbox[rel-734-581804753]\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"667\" src=\"https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2022\/09\/06-mario-lozito-3.jpg\" class=\"attachment-full\" alt=\"\" srcset=\"https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2022\/09\/06-mario-lozito-3.jpg 1000w, https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2022\/09\/06-mario-lozito-3-300x200.jpg 300w, https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2022\/09\/06-mario-lozito-3-768x512.jpg 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><\/div><\/div><div class=\"vc_item\"><div class=\"vc_inner\"><a class=\"\" href=\"https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2023\/06\/06-mario-lozito-2.jpg\" data-lightbox=\"lightbox[rel-734-581804753]\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2023\/06\/06-mario-lozito-2.jpg\" class=\"attachment-full\" alt=\"\" srcset=\"https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2023\/06\/06-mario-lozito-2.jpg 800w, https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2023\/06\/06-mario-lozito-2-300x200.jpg 300w, https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2023\/06\/06-mario-lozito-2-768x512.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-8\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">A different pastoral, symbol of episcopal power but also thorny and twisted in its forms, to highlight the pitfalls they find during their mandate, an abbess also dark and mysterious almost wrapped in dark magic.<\/span><\/p>\n<div id=\"audioigniter-1142\" class=\"audioigniter-root\" data-player-type=\"simple\" data-tracks-url=\"https:\/\/www.prolococastellanagrotte.it\/en\/?audioigniter_playlist_id=1142\" data-display-track-no=\"false\" data-reverse-track-order=\"false\" data-display-tracklist-covers=\"true\" data-display-active-cover=\"true\" data-display-artist-names=\"false\" data-display-buy-buttons=\"false\" data-buy-buttons-target=\"false\" data-cycle-tracks=\"false\" data-display-credits=\"false\" data-display-tracklist=\"true\" data-allow-tracklist-toggle=\"true\" data-allow-tracklist-loop=\"true\" data-limit-tracklist-height=\"true\" data-volume=\"100\" data-tracklist-height=\"185\" ><\/div>\n<p style=\"text-align: right;\"><span style=\"font-size: 14pt;\"><strong>Mario Lozito<br \/>\n<\/strong><\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: center;\"><span style=\"font-size: 13pt;\"><strong>Do you have a door on the path you want to nominate? <a href=\"mailto:prolococastellanagrotte@gmail.com?subject=Porta%20da%20candidare%20per%20le%20Badesse\">Click here<\/a><\/strong><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 13pt;\"><strong>Do you also want to participate in the next edition? <a href=\"mailto:prolococastellanagrotte@gmail.com?subject=Voglio%20partecipare%20alla%20prossima%20edizione%20delle%20Badesse\">Click here<\/a><\/strong><\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid gino\"><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_left\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<a class=\"\" data-lightbox=\"lightbox[rel-734-2608890925]\" href=\"https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2022\/09\/06-mario-lozito-1.jpg\" target=\"_self\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2022\/09\/06-mario-lozito-1.jpg\" class=\"vc_single_image-img attachment-full\" alt=\"\" srcset=\"https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2022\/09\/06-mario-lozito-1.jpg 800w, https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2022\/09\/06-mario-lozito-1-300x200.jpg 300w, https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2022\/09\/06-mario-lozito-1-768x512.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_left\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<a class=\"\" data-lightbox=\"lightbox[rel-734-2402018506]\" href=\"https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2022\/09\/06-mario-lozito-4.jpg\" target=\"_self\"><img loading=\"lazy\" decoding=\"async\" width=\"667\" height=\"1000\" src=\"https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2022\/09\/06-mario-lozito-4.jpg\" class=\"vc_single_image-img attachment-full\" alt=\"\" srcset=\"https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2022\/09\/06-mario-lozito-4.jpg 667w, https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2022\/09\/06-mario-lozito-4-200x300.jpg 200w\" sizes=\"auto, (max-width: 667px) 100vw, 667px\" \/><\/a>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_left\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<a class=\"\" data-lightbox=\"lightbox[rel-734-2582423245]\" href=\"https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2022\/09\/06-mario-lozito-5.jpg\" target=\"_self\"><img loading=\"lazy\" decoding=\"async\" width=\"533\" height=\"800\" src=\"https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2022\/09\/06-mario-lozito-5.jpg\" class=\"vc_single_image-img attachment-full\" alt=\"\" srcset=\"https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2022\/09\/06-mario-lozito-5.jpg 533w, https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2022\/09\/06-mario-lozito-5-200x300.jpg 200w\" sizes=\"auto, (max-width: 533px) 100vw, 533px\" \/><\/a>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid gino\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: center;\"><span style=\"font-size: 18pt;\"><strong>Where it is and how to get there (Reference n.25)<\/strong><\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid gino\"><div class=\"ciccio wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_left\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" data-vc-zoom=\"https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2024\/10\/mappa-669x1024.jpg\" width=\"1045\" height=\"1600\" src=\"https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2024\/10\/mappa.jpg\" class=\"vc_single_image-img attachment-full\" alt=\"\" srcset=\"https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2024\/10\/mappa.jpg 1045w, https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2024\/10\/mappa-196x300.jpg 196w, https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2024\/10\/mappa-669x1024.jpg 669w, https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2024\/10\/mappa-768x1176.jpg 768w, https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2024\/10\/mappa-1003x1536.jpg 1003w, https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2024\/10\/mappa-8x12.jpg 8w\" sizes=\"auto, (max-width: 1045px) 100vw, 1045px\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_raw_code wpb_content_element wpb_raw_html\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n            <div \n                class=\"elfsight-widget-google-maps elfsight-widget\" \n                data-elfsight-google-maps-options=\"%7B%22categoriesEnabled%22%3Afalse%2C%22categories%22%3A%5B%5D%2C%22icons%22%3A%5B%7B%22value%22%3A%22%22%2C%22name%22%3A%22%20-%20None%20-%20%22%2C%22visible%22%3Afalse%7D%2C%7B%22value%22%3A%229361a380-1e92-4303-8aa2-7e8c2c073469%22%2C%22name%22%3A%22star%22%2C%22preview%22%3A%22https%3A%5C%2F%5C%2Fassets-elfsight-com.sfo2.digitaloceanspaces.com%5C%2Fapps%5C%2Fgoogle-maps%5C%2Fmarkers%5C%2Fmarker-star.svg%22%2C%22iconType%22%3A%22library%22%2C%22iconLibrary%22%3A%22star%22%2C%22iconCustom%22%3Anull%2C%22iconColor%22%3A%22%22%2C%22iconSize%22%3A32%7D%5D%2C%22lang%22%3A%22it%22%2C%22distanceUnits%22%3A%22km%22%2C%22markers%22%3A%5B%7B%22position%22%3A%2240.88571585075622%2C%2017.169015431905372%22%2C%22coordinates%22%3A%2240.88571585075622%2C%2017.169015431905372%22%2C%22infoTitle%22%3A%229%20-%20pastorale%20optical%22%2C%22category%22%3A%22%22%2C%22icon%22%3A%22%22%2C%22infoDescription%22%3A%22%22%2C%22infoImage%22%3A%22https%3A%5C%2F%5C%2Fwww.prolococastellanagrotte.it%5C%2Fwp-content%5C%2Fuploads%5C%2F2022%5C%2F09%5C%2F06-mario-lozito-5.jpg%22%2C%22infoAddress%22%3A%22Via%20Don%20Pietro%20Giannuzzi%22%2C%22infoSite%22%3A%22%22%2C%22infoPhone%22%3A%22%22%2C%22infoEmail%22%3A%22%22%2C%22infoWorkingHours%22%3A%22%22%2C%22markerClickAction%22%3A%22infoWindow%22%2C%22infoWindowOpenedByDefault%22%3Afalse%2C%22linkUrl%22%3A%22%22%2C%22animation%22%3A%22drop%22%7D%5D%2C%22mapType%22%3A%22roadmap%22%2C%22center%22%3A%22auto%22%2C%22zoom%22%3A%22auto%22%2C%22controls%22%3A%5B%22zoom%22%2C%22mapType%22%2C%22scale%22%2C%22streetView%22%2C%22rotate%22%2C%22fullScreen%22%5D%2C%22markerClusterEnabled%22%3Atrue%2C%22markerClusterZoom%22%3Atrue%2C%22markerClusterMin%22%3A2%2C%22markerClusterIcon%22%3A%22default%22%2C%22markerClusterIconColor%22%3A%22%22%2C%22markerClusterIconUrl%22%3Anull%2C%22markerClusterSize%22%3A52%2C%22infoDirections%22%3Atrue%2C%22directionsTarget%22%3A%22google%22%2C%22scrollwheel%22%3Afalse%2C%22draggable%22%3Atrue%2C%22layers%22%3A%5B%5D%2C%22width%22%3A%22auto%22%2C%22height%22%3A%22850%22%2C%22panelEnabled%22%3Afalse%2C%22panelOpenByDefault%22%3Atrue%2C%22panelSearchVisible%22%3Atrue%2C%22panelSearchBy%22%3A%22markers%22%2C%22panelSearchPlaceholder%22%3A%22%22%2C%22panelListItemElements%22%3A%5B%22title%22%2C%22category%22%2C%22image%22%2C%22address%22%2C%22phone%22%2C%22workingHours%22%5D%2C%22mainColor%22%3A%22rgb%2866%2C%20133%2C%20244%29%22%2C%22style%22%3A%22custom%22%2C%22colorGeometry%22%3A%22rgb%28235%2C%20227%2C%20205%29%22%2C%22colorLabelsTextFill%22%3A%22rgb%2882%2C%2055%2C%2053%29%22%2C%22colorLabelsTextStroke%22%3A%22rgba%28245%2C241%2C230%2C1%29%22%2C%22colorAdministrativeGeometryStroke%22%3A%22rgba%28201%2C178%2C166%2C1%29%22%2C%22colorAdministrativeLandParcel%22%3A%22rgba%28174%2C158%2C144%2C1%29%22%2C%22colorLandscapeNaturalGeometry%22%3A%22rgba%28223%2C210%2C174%2C1%29%22%2C%22colorPoiGeometry%22%3A%22rgba%28223%2C210%2C174%2C1%29%22%2C%22colorPoiLabelsTextFill%22%3A%22rgba%28147%2C129%2C124%2C1%29%22%2C%22colorPoiParkGeometryFill%22%3A%22rgba%28165%2C176%2C118%2C1%29%22%2C%22colorPoiParkLabelsTextFill%22%3A%22rgba%2868%2C117%2C48%2C1%29%22%2C%22colorRoadGeometry%22%3A%22rgba%28245%2C241%2C230%2C1%29%22%2C%22colorRoadArterial%22%3A%22rgba%28253%2C252%2C248%2C1%29%22%2C%22colorRoadHighway%22%3A%22rgba%28248%2C201%2C103%2C1%29%22%2C%22colorRoadHighwayGeometryStroke%22%3A%22rgba%28233%2C188%2C98%2C1%29%22%2C%22colorRoadHighwayControlledAccessGeometry%22%3A%22rgba%28233%2C141%2C88%2C1%29%22%2C%22colorRoadHighwayControlledAccessGeometryStroke%22%3A%22rgba%28219%2C133%2C85%2C1%29%22%2C%22colorRoadLocalLabelsTextFill%22%3A%22rgba%28128%2C107%2C99%2C1%29%22%2C%22colorTransitLineGeometry%22%3A%22rgba%28223%2C210%2C174%2C1%29%22%2C%22colorTransitLineLabelsTextFill%22%3A%22rgba%28143%2C125%2C119%2C1%29%22%2C%22colorTransitLineLabelsTextStroke%22%3A%22rgba%28235%2C227%2C205%2C1%29%22%2C%22colorTransitStationGeometry%22%3A%22rgba%28223%2C210%2C174%2C1%29%22%2C%22colorWaterGeometryFill%22%3A%22rgba%28185%2C211%2C194%2C1%29%22%2C%22colorWaterLabelTextFill%22%3A%22rgba%28146%2C153%2C141%2C1%29%22%2C%22customGoogleMapsStyles%22%3A%22%22%2C%22apiKey%22%3A%22AIzaSyDuLxATglMSkmUM8pYqCfJkrn1X-mOmHTo%22%2C%22widgetId%22%3A%2238%22%7D\" \n                data-elfsight-google-maps-version=\"2.4.2\"\n                data-elfsight-widget-id=\"elfsight-google-maps-38\">\n            <\/div>\n            \n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"Visualizza la mappa interattiva completa delle porte della Badessa Un pastorale diverso, simbolo del potere vescovile ma anche spinoso e contorto nelle sue forme, per risaltare le insidie che esse trovano nel corso del loro mandato, una badessa anche tenebrosa e misteriosa quasi avvolta da una magia oscura. Mario Lozito<div class=\"re-read-more\"><a class=\"read-more\" href=\"https:\/\/www.prolococastellanagrotte.it\/en\/9-pastorale-optical-mario-lozito\/\">Read More...<\/a><\/div>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"full-width.php","meta":{"footnotes":""},"class_list":["post-734","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>25 - Badessa - Pastorale optical - Pro Loco Castellana Grotte | Don Nicola Pellegrino<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.prolococastellanagrotte.it\/en\/9-pastorale-optical-mario-lozito\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"25 - Badessa - Pastorale optical - Pro Loco Castellana Grotte | Don Nicola Pellegrino\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.prolococastellanagrotte.it\/en\/9-pastorale-optical-mario-lozito\/\" \/>\n<meta property=\"og:site_name\" content=\"Pro Loco Castellana Grotte | Don Nicola Pellegrino\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-30T10:09:34+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2021\/11\/maps-icon-16-300x300.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.prolococastellanagrotte.it\\\/9-pastorale-optical-mario-lozito\\\/\",\"url\":\"https:\\\/\\\/www.prolococastellanagrotte.it\\\/9-pastorale-optical-mario-lozito\\\/\",\"name\":\"25 - Badessa - Pastorale optical - Pro Loco Castellana Grotte | Don Nicola Pellegrino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.prolococastellanagrotte.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.prolococastellanagrotte.it\\\/9-pastorale-optical-mario-lozito\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.prolococastellanagrotte.it\\\/9-pastorale-optical-mario-lozito\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.prolococastellanagrotte.it\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/maps-icon-16-300x300.png\",\"datePublished\":\"2022-09-19T11:53:58+00:00\",\"dateModified\":\"2024-10-30T10:09:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.prolococastellanagrotte.it\\\/9-pastorale-optical-mario-lozito\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.prolococastellanagrotte.it\\\/9-pastorale-optical-mario-lozito\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.prolococastellanagrotte.it\\\/9-pastorale-optical-mario-lozito\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.prolococastellanagrotte.it\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/maps-icon-16-300x300.png\",\"contentUrl\":\"http:\\\/\\\/www.prolococastellanagrotte.it\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/maps-icon-16-300x300.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.prolococastellanagrotte.it\\\/9-pastorale-optical-mario-lozito\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.prolococastellanagrotte.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"25 &#8211; Badessa &#8211; Pastorale optical\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.prolococastellanagrotte.it\\\/#website\",\"url\":\"https:\\\/\\\/www.prolococastellanagrotte.it\\\/\",\"name\":\"Pro Loco Castellana Grotte | Don Nicola Pellegrino\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.prolococastellanagrotte.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.prolococastellanagrotte.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.prolococastellanagrotte.it\\\/#organization\",\"name\":\"Pro Loco Castellana Grotte | Don Nicola Pellegrino\",\"url\":\"https:\\\/\\\/www.prolococastellanagrotte.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.prolococastellanagrotte.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.prolococastellanagrotte.it\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/cropped-logos_definitivo.png\",\"contentUrl\":\"https:\\\/\\\/www.prolococastellanagrotte.it\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/cropped-logos_definitivo.png\",\"width\":300,\"height\":157,\"caption\":\"Pro Loco Castellana Grotte | Don Nicola Pellegrino\"},\"image\":{\"@id\":\"https:\\\/\\\/www.prolococastellanagrotte.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"25 - Badessa - Pastorale optical - Pro Loco Castellana Grotte | Don Nicola Pellegrino","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.prolococastellanagrotte.it\/en\/9-pastorale-optical-mario-lozito\/","og_locale":"en_US","og_type":"article","og_title":"25 - Badessa - Pastorale optical - Pro Loco Castellana Grotte | Don Nicola Pellegrino","og_url":"https:\/\/www.prolococastellanagrotte.it\/en\/9-pastorale-optical-mario-lozito\/","og_site_name":"Pro Loco Castellana Grotte | Don Nicola Pellegrino","article_modified_time":"2024-10-30T10:09:34+00:00","og_image":[{"url":"http:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2021\/11\/maps-icon-16-300x300.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.prolococastellanagrotte.it\/9-pastorale-optical-mario-lozito\/","url":"https:\/\/www.prolococastellanagrotte.it\/9-pastorale-optical-mario-lozito\/","name":"25 - Badessa - Pastorale optical - Pro Loco Castellana Grotte | Don Nicola Pellegrino","isPartOf":{"@id":"https:\/\/www.prolococastellanagrotte.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.prolococastellanagrotte.it\/9-pastorale-optical-mario-lozito\/#primaryimage"},"image":{"@id":"https:\/\/www.prolococastellanagrotte.it\/9-pastorale-optical-mario-lozito\/#primaryimage"},"thumbnailUrl":"http:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2021\/11\/maps-icon-16-300x300.png","datePublished":"2022-09-19T11:53:58+00:00","dateModified":"2024-10-30T10:09:34+00:00","breadcrumb":{"@id":"https:\/\/www.prolococastellanagrotte.it\/9-pastorale-optical-mario-lozito\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.prolococastellanagrotte.it\/9-pastorale-optical-mario-lozito\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.prolococastellanagrotte.it\/9-pastorale-optical-mario-lozito\/#primaryimage","url":"http:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2021\/11\/maps-icon-16-300x300.png","contentUrl":"http:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2021\/11\/maps-icon-16-300x300.png"},{"@type":"BreadcrumbList","@id":"https:\/\/www.prolococastellanagrotte.it\/9-pastorale-optical-mario-lozito\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.prolococastellanagrotte.it\/"},{"@type":"ListItem","position":2,"name":"25 &#8211; Badessa &#8211; Pastorale optical"}]},{"@type":"WebSite","@id":"https:\/\/www.prolococastellanagrotte.it\/#website","url":"https:\/\/www.prolococastellanagrotte.it\/","name":"Pro Loco Castellana Grotte | Don Nicola Pellegrino","description":"","publisher":{"@id":"https:\/\/www.prolococastellanagrotte.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.prolococastellanagrotte.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.prolococastellanagrotte.it\/#organization","name":"Pro Loco Castellana Grotte | Don Nicola Pellegrino","url":"https:\/\/www.prolococastellanagrotte.it\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.prolococastellanagrotte.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2021\/11\/cropped-logos_definitivo.png","contentUrl":"https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2021\/11\/cropped-logos_definitivo.png","width":300,"height":157,"caption":"Pro Loco Castellana Grotte | Don Nicola Pellegrino"},"image":{"@id":"https:\/\/www.prolococastellanagrotte.it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.prolococastellanagrotte.it\/en\/wp-json\/wp\/v2\/pages\/734","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.prolococastellanagrotte.it\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.prolococastellanagrotte.it\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.prolococastellanagrotte.it\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.prolococastellanagrotte.it\/en\/wp-json\/wp\/v2\/comments?post=734"}],"version-history":[{"count":10,"href":"https:\/\/www.prolococastellanagrotte.it\/en\/wp-json\/wp\/v2\/pages\/734\/revisions"}],"predecessor-version":[{"id":2028,"href":"https:\/\/www.prolococastellanagrotte.it\/en\/wp-json\/wp\/v2\/pages\/734\/revisions\/2028"}],"wp:attachment":[{"href":"https:\/\/www.prolococastellanagrotte.it\/en\/wp-json\/wp\/v2\/media?parent=734"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}