{"id":723,"date":"2022-09-19T12:47:09","date_gmt":"2022-09-19T10:47:09","guid":{"rendered":"https:\/\/www.prolococastellanagrotte.it\/?page_id=723"},"modified":"2024-10-30T11:08:51","modified_gmt":"2024-10-30T10:08:51","slug":"8-le-tentazioni-della-badessa-nitti-maria","status":"publish","type":"page","link":"https:\/\/www.prolococastellanagrotte.it\/en\/8-le-tentazioni-della-badessa-nitti-maria\/","title":{"rendered":"24 &#8211; Badessa &#8211; Tentazioni della badessa"},"content":{"rendered":"<div class=\"vc_row wpb_row vc_row-fluid gino\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: center;\"><span style=\"font-size: 18pt;\"><strong><span style=\"color: #ff6d09;\"><a href=\"\/en\/mappa-completa-le-porte-della-badessa\/#mappacompleta\"><span style=\"font-size: 14pt;\">Visualizza la mappa interattiva completa delle porte della Badessa<\/span><\/a><br \/>\n<a href=\"\/en\/mappa-completa-le-porte-della-badessa\/#mappacompleta\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-299\" src=\"http:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2021\/11\/maps-icon-16-300x300.png\" alt=\"\" width=\"77\" height=\"77\" srcset=\"https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2021\/11\/maps-icon-16-300x300.png 300w, https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2021\/11\/maps-icon-16-150x150.png 150w, https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2021\/11\/maps-icon-16-100x100.png 100w, https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2021\/11\/maps-icon-16.png 320w\" sizes=\"auto, (max-width: 77px) 100vw, 77px\" \/><\/a><\/span><\/strong><\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_row wpb_row vc_inner vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_left\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" width=\"899\" height=\"723\" src=\"https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2023\/06\/artista.jpg\" class=\"vc_single_image-img attachment-full\" alt=\"\" srcset=\"https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2023\/06\/artista.jpg 899w, https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2023\/06\/artista-300x241.jpg 300w, https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2023\/06\/artista-768x618.jpg 768w\" sizes=\"auto, (max-width: 899px) 100vw, 899px\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-8\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">The Abbess is surrounded by her fears, doubts, renunciations, remorse and anxieties that climb up her dress in the form of skeletons, trying to drag her along with them to perdition. The only source and force necessary for salvation is prayer. The Mitra, symbol of episcopal power; necessary courage to remove his doubts and accept his destiny. \u201cOh Lord, let me accept my destiny, give me strength and keep away from me avarice, lust, envy, pride, fears and uncertainties. Give me peace and serenity, so that I can resign myself to this life of deprivation that my family has decided for me&quot;.<\/span><\/p>\n<div id=\"audioigniter-1139\" class=\"audioigniter-root\" data-player-type=\"simple\" data-tracks-url=\"https:\/\/www.prolococastellanagrotte.it\/en\/?audioigniter_playlist_id=1139\" data-display-track-no=\"false\" data-reverse-track-order=\"false\" data-display-tracklist-covers=\"true\" data-display-active-cover=\"true\" data-display-artist-names=\"false\" data-display-buy-buttons=\"false\" data-buy-buttons-target=\"false\" data-cycle-tracks=\"false\" data-display-credits=\"false\" data-display-tracklist=\"true\" data-allow-tracklist-toggle=\"true\" data-allow-tracklist-loop=\"true\" data-limit-tracklist-height=\"true\" data-volume=\"100\" data-tracklist-height=\"185\" ><\/div>\n<p style=\"text-align: right;\"><span style=\"font-size: 14pt;\"><strong>Nitti Maria<\/strong><\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: center;\"><span style=\"font-size: 13pt;\"><strong>Do you have a door on the path you want to nominate? <a href=\"mailto:prolococastellanagrotte@gmail.com?subject=Porta%20da%20candidare%20per%20le%20Badesse\">Click here<\/a><\/strong><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 13pt;\"><strong>Do you also want to participate in the next edition? <a href=\"mailto:prolococastellanagrotte@gmail.com?subject=Voglio%20partecipare%20alla%20prossima%20edizione%20delle%20Badesse\">Click here<\/a><\/strong><\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid gino\"><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<a class=\"\" data-lightbox=\"lightbox[rel-723-2769179709]\" href=\"https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2022\/09\/WhatsApp-Image-2022-09-16-at-12.36.13-682x1024.jpeg\" target=\"_self\"><img loading=\"lazy\" decoding=\"async\" width=\"1066\" height=\"1600\" src=\"https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2022\/09\/WhatsApp-Image-2022-09-16-at-12.36.13.jpeg\" class=\"vc_single_image-img attachment-full\" alt=\"\" srcset=\"https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2022\/09\/WhatsApp-Image-2022-09-16-at-12.36.13.jpeg 1066w, https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2022\/09\/WhatsApp-Image-2022-09-16-at-12.36.13-200x300.jpeg 200w, https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2022\/09\/WhatsApp-Image-2022-09-16-at-12.36.13-682x1024.jpeg 682w, https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2022\/09\/WhatsApp-Image-2022-09-16-at-12.36.13-768x1153.jpeg 768w, https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2022\/09\/WhatsApp-Image-2022-09-16-at-12.36.13-1023x1536.jpeg 1023w\" sizes=\"auto, (max-width: 1066px) 100vw, 1066px\" \/><\/a>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<a class=\"\" data-lightbox=\"lightbox[rel-723-234564595]\" href=\"https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2023\/06\/1668969395277-1024x1024.webp\" target=\"_self\"><img loading=\"lazy\" decoding=\"async\" width=\"1066\" height=\"1066\" src=\"https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2023\/06\/1668969395277.webp\" class=\"vc_single_image-img attachment-full\" alt=\"\" srcset=\"https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2023\/06\/1668969395277.webp 1066w, https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2023\/06\/1668969395277-300x300.webp 300w, https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2023\/06\/1668969395277-1024x1024.webp 1024w, https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2023\/06\/1668969395277-150x150.webp 150w, https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2023\/06\/1668969395277-768x768.webp 768w\" sizes=\"auto, (max-width: 1066px) 100vw, 1066px\" \/><\/a>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<a class=\"\" data-lightbox=\"lightbox[rel-723-2063427801]\" href=\"https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2023\/06\/Immagine-WhatsApp-2023-06-29-ore-16.49.02-576x1024.jpg\" target=\"_self\"><img loading=\"lazy\" decoding=\"async\" width=\"899\" height=\"1599\" src=\"https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2023\/06\/Immagine-WhatsApp-2023-06-29-ore-16.49.02.jpg\" class=\"vc_single_image-img attachment-full\" alt=\"\" srcset=\"https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2023\/06\/Immagine-WhatsApp-2023-06-29-ore-16.49.02.jpg 899w, https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2023\/06\/Immagine-WhatsApp-2023-06-29-ore-16.49.02-169x300.jpg 169w, https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2023\/06\/Immagine-WhatsApp-2023-06-29-ore-16.49.02-576x1024.jpg 576w, https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2023\/06\/Immagine-WhatsApp-2023-06-29-ore-16.49.02-768x1366.jpg 768w, https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2023\/06\/Immagine-WhatsApp-2023-06-29-ore-16.49.02-864x1536.jpg 864w\" sizes=\"auto, (max-width: 899px) 100vw, 899px\" \/><\/a>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid gino\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: center;\"><span style=\"font-size: 18pt;\"><strong>Where it is and how to get there (Reference n.24)<\/strong><\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid gino\"><div class=\"ciccio wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_left\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" data-vc-zoom=\"https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2024\/10\/mappa-669x1024.jpg\" width=\"1045\" height=\"1600\" src=\"https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2024\/10\/mappa.jpg\" class=\"vc_single_image-img attachment-full\" alt=\"\" srcset=\"https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2024\/10\/mappa.jpg 1045w, https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2024\/10\/mappa-196x300.jpg 196w, https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2024\/10\/mappa-669x1024.jpg 669w, https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2024\/10\/mappa-768x1176.jpg 768w, https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2024\/10\/mappa-1003x1536.jpg 1003w, https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2024\/10\/mappa-8x12.jpg 8w\" sizes=\"auto, (max-width: 1045px) 100vw, 1045px\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_raw_code wpb_content_element wpb_raw_html\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n            <div \n                class=\"elfsight-widget-google-maps elfsight-widget\" \n                data-elfsight-google-maps-options=\"%7B%22categoriesEnabled%22%3Afalse%2C%22categories%22%3A%5B%5D%2C%22icons%22%3A%5B%7B%22value%22%3A%22%22%2C%22name%22%3A%22%20-%20None%20-%20%22%2C%22visible%22%3Afalse%7D%2C%7B%22value%22%3A%229361a380-1e92-4303-8aa2-7e8c2c073469%22%2C%22name%22%3A%22star%22%2C%22preview%22%3A%22https%3A%5C%2F%5C%2Fassets-elfsight-com.sfo2.digitaloceanspaces.com%5C%2Fapps%5C%2Fgoogle-maps%5C%2Fmarkers%5C%2Fmarker-star.svg%22%2C%22iconType%22%3A%22library%22%2C%22iconLibrary%22%3A%22star%22%2C%22iconCustom%22%3Anull%2C%22iconColor%22%3A%22%22%2C%22iconSize%22%3A32%7D%5D%2C%22lang%22%3A%22it%22%2C%22distanceUnits%22%3A%22km%22%2C%22markers%22%3A%5B%7B%22position%22%3A%2240.88571331601279%2C%2017.16897452821922%22%2C%22coordinates%22%3A%2240.88571331601279%2C%2017.16897452821922%22%2C%22infoTitle%22%3A%228%20-%20le%20tentazioni%20della%20badessa%22%2C%22category%22%3A%22%22%2C%22icon%22%3A%22%22%2C%22infoDescription%22%3A%22%22%2C%22infoImage%22%3A%22https%3A%5C%2F%5C%2Fwww.prolococastellanagrotte.it%5C%2Fwp-content%5C%2Fuploads%5C%2F2022%5C%2F09%5C%2FWhatsApp-Image-2022-09-16-at-12.36.13.jpeg%22%2C%22infoAddress%22%3A%22Via%20Don%20Pietro%20Giannuzzi%22%2C%22infoSite%22%3A%22%22%2C%22infoPhone%22%3A%22%22%2C%22infoEmail%22%3A%22%22%2C%22infoWorkingHours%22%3A%22%22%2C%22markerClickAction%22%3A%22infoWindow%22%2C%22infoWindowOpenedByDefault%22%3Afalse%2C%22linkUrl%22%3A%22%22%2C%22animation%22%3A%22drop%22%7D%5D%2C%22mapType%22%3A%22roadmap%22%2C%22center%22%3A%22auto%22%2C%22zoom%22%3A%22auto%22%2C%22controls%22%3A%5B%22zoom%22%2C%22mapType%22%2C%22scale%22%2C%22streetView%22%2C%22rotate%22%2C%22fullScreen%22%5D%2C%22markerClusterEnabled%22%3Atrue%2C%22markerClusterZoom%22%3Atrue%2C%22markerClusterMin%22%3A2%2C%22markerClusterIcon%22%3A%22default%22%2C%22markerClusterIconColor%22%3A%22%22%2C%22markerClusterIconUrl%22%3Anull%2C%22markerClusterSize%22%3A52%2C%22infoDirections%22%3Atrue%2C%22directionsTarget%22%3A%22google%22%2C%22scrollwheel%22%3Afalse%2C%22draggable%22%3Atrue%2C%22layers%22%3A%5B%5D%2C%22width%22%3A%22auto%22%2C%22height%22%3A%22850%22%2C%22panelEnabled%22%3Afalse%2C%22panelOpenByDefault%22%3Atrue%2C%22panelSearchVisible%22%3Atrue%2C%22panelSearchBy%22%3A%22markers%22%2C%22panelSearchPlaceholder%22%3A%22%22%2C%22panelListItemElements%22%3A%5B%22title%22%2C%22category%22%2C%22image%22%2C%22address%22%2C%22phone%22%2C%22workingHours%22%5D%2C%22mainColor%22%3A%22rgb%2866%2C%20133%2C%20244%29%22%2C%22style%22%3A%22custom%22%2C%22colorGeometry%22%3A%22rgb%28235%2C%20227%2C%20205%29%22%2C%22colorLabelsTextFill%22%3A%22rgb%2882%2C%2055%2C%2053%29%22%2C%22colorLabelsTextStroke%22%3A%22rgba%28245%2C241%2C230%2C1%29%22%2C%22colorAdministrativeGeometryStroke%22%3A%22rgba%28201%2C178%2C166%2C1%29%22%2C%22colorAdministrativeLandParcel%22%3A%22rgba%28174%2C158%2C144%2C1%29%22%2C%22colorLandscapeNaturalGeometry%22%3A%22rgba%28223%2C210%2C174%2C1%29%22%2C%22colorPoiGeometry%22%3A%22rgba%28223%2C210%2C174%2C1%29%22%2C%22colorPoiLabelsTextFill%22%3A%22rgba%28147%2C129%2C124%2C1%29%22%2C%22colorPoiParkGeometryFill%22%3A%22rgba%28165%2C176%2C118%2C1%29%22%2C%22colorPoiParkLabelsTextFill%22%3A%22rgba%2868%2C117%2C48%2C1%29%22%2C%22colorRoadGeometry%22%3A%22rgba%28245%2C241%2C230%2C1%29%22%2C%22colorRoadArterial%22%3A%22rgba%28253%2C252%2C248%2C1%29%22%2C%22colorRoadHighway%22%3A%22rgba%28248%2C201%2C103%2C1%29%22%2C%22colorRoadHighwayGeometryStroke%22%3A%22rgba%28233%2C188%2C98%2C1%29%22%2C%22colorRoadHighwayControlledAccessGeometry%22%3A%22rgba%28233%2C141%2C88%2C1%29%22%2C%22colorRoadHighwayControlledAccessGeometryStroke%22%3A%22rgba%28219%2C133%2C85%2C1%29%22%2C%22colorRoadLocalLabelsTextFill%22%3A%22rgba%28128%2C107%2C99%2C1%29%22%2C%22colorTransitLineGeometry%22%3A%22rgba%28223%2C210%2C174%2C1%29%22%2C%22colorTransitLineLabelsTextFill%22%3A%22rgba%28143%2C125%2C119%2C1%29%22%2C%22colorTransitLineLabelsTextStroke%22%3A%22rgba%28235%2C227%2C205%2C1%29%22%2C%22colorTransitStationGeometry%22%3A%22rgba%28223%2C210%2C174%2C1%29%22%2C%22colorWaterGeometryFill%22%3A%22rgba%28185%2C211%2C194%2C1%29%22%2C%22colorWaterLabelTextFill%22%3A%22rgba%28146%2C153%2C141%2C1%29%22%2C%22customGoogleMapsStyles%22%3A%22%22%2C%22apiKey%22%3A%22AIzaSyDuLxATglMSkmUM8pYqCfJkrn1X-mOmHTo%22%2C%22widgetId%22%3A%2237%22%7D\" \n                data-elfsight-google-maps-version=\"2.4.2\"\n                data-elfsight-widget-id=\"elfsight-google-maps-37\">\n            <\/div>\n            \n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"Visualizza la mappa interattiva completa delle porte della Badessa La Badessa \u00e8 circondata dalle sue paure, dubbi, rinunce, rimorsi ed ansie che si arrampicano sottoforma di scheletri sul suo abito, cercando di trascinarla con loro nella perdizione. Unica fonte e forza necessaria per la salvezza \u00e8 la preghiera. La Mitra,<div class=\"re-read-more\"><a class=\"read-more\" href=\"https:\/\/www.prolococastellanagrotte.it\/en\/8-le-tentazioni-della-badessa-nitti-maria\/\">Read More...<\/a><\/div>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"full-width.php","meta":{"footnotes":""},"class_list":["post-723","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>24 - Badessa - Tentazioni della badessa - Pro Loco Castellana Grotte | Don Nicola Pellegrino<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.prolococastellanagrotte.it\/en\/8-le-tentazioni-della-badessa-nitti-maria\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"24 - Badessa - Tentazioni della badessa - Pro Loco Castellana Grotte | Don Nicola Pellegrino\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.prolococastellanagrotte.it\/en\/8-le-tentazioni-della-badessa-nitti-maria\/\" \/>\n<meta property=\"og:site_name\" content=\"Pro Loco Castellana Grotte | Don Nicola Pellegrino\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-30T10:08:51+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2021\/11\/maps-icon-16-300x300.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.prolococastellanagrotte.it\\\/8-le-tentazioni-della-badessa-nitti-maria\\\/\",\"url\":\"https:\\\/\\\/www.prolococastellanagrotte.it\\\/8-le-tentazioni-della-badessa-nitti-maria\\\/\",\"name\":\"24 - Badessa - Tentazioni della badessa - Pro Loco Castellana Grotte | Don Nicola Pellegrino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.prolococastellanagrotte.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.prolococastellanagrotte.it\\\/8-le-tentazioni-della-badessa-nitti-maria\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.prolococastellanagrotte.it\\\/8-le-tentazioni-della-badessa-nitti-maria\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.prolococastellanagrotte.it\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/maps-icon-16-300x300.png\",\"datePublished\":\"2022-09-19T10:47:09+00:00\",\"dateModified\":\"2024-10-30T10:08:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.prolococastellanagrotte.it\\\/8-le-tentazioni-della-badessa-nitti-maria\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.prolococastellanagrotte.it\\\/8-le-tentazioni-della-badessa-nitti-maria\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.prolococastellanagrotte.it\\\/8-le-tentazioni-della-badessa-nitti-maria\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.prolococastellanagrotte.it\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/maps-icon-16-300x300.png\",\"contentUrl\":\"http:\\\/\\\/www.prolococastellanagrotte.it\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/maps-icon-16-300x300.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.prolococastellanagrotte.it\\\/8-le-tentazioni-della-badessa-nitti-maria\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.prolococastellanagrotte.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"24 &#8211; Badessa &#8211; Tentazioni della badessa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.prolococastellanagrotte.it\\\/#website\",\"url\":\"https:\\\/\\\/www.prolococastellanagrotte.it\\\/\",\"name\":\"Pro Loco Castellana Grotte | Don Nicola Pellegrino\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.prolococastellanagrotte.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.prolococastellanagrotte.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.prolococastellanagrotte.it\\\/#organization\",\"name\":\"Pro Loco Castellana Grotte | Don Nicola Pellegrino\",\"url\":\"https:\\\/\\\/www.prolococastellanagrotte.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.prolococastellanagrotte.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.prolococastellanagrotte.it\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/cropped-logos_definitivo.png\",\"contentUrl\":\"https:\\\/\\\/www.prolococastellanagrotte.it\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/cropped-logos_definitivo.png\",\"width\":300,\"height\":157,\"caption\":\"Pro Loco Castellana Grotte | Don Nicola Pellegrino\"},\"image\":{\"@id\":\"https:\\\/\\\/www.prolococastellanagrotte.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"24 - Badessa - Tentazioni della badessa - Pro Loco Castellana Grotte | Don Nicola Pellegrino","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.prolococastellanagrotte.it\/en\/8-le-tentazioni-della-badessa-nitti-maria\/","og_locale":"en_US","og_type":"article","og_title":"24 - Badessa - Tentazioni della badessa - Pro Loco Castellana Grotte | Don Nicola Pellegrino","og_url":"https:\/\/www.prolococastellanagrotte.it\/en\/8-le-tentazioni-della-badessa-nitti-maria\/","og_site_name":"Pro Loco Castellana Grotte | Don Nicola Pellegrino","article_modified_time":"2024-10-30T10:08:51+00:00","og_image":[{"url":"http:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2021\/11\/maps-icon-16-300x300.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.prolococastellanagrotte.it\/8-le-tentazioni-della-badessa-nitti-maria\/","url":"https:\/\/www.prolococastellanagrotte.it\/8-le-tentazioni-della-badessa-nitti-maria\/","name":"24 - Badessa - Tentazioni della badessa - Pro Loco Castellana Grotte | Don Nicola Pellegrino","isPartOf":{"@id":"https:\/\/www.prolococastellanagrotte.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.prolococastellanagrotte.it\/8-le-tentazioni-della-badessa-nitti-maria\/#primaryimage"},"image":{"@id":"https:\/\/www.prolococastellanagrotte.it\/8-le-tentazioni-della-badessa-nitti-maria\/#primaryimage"},"thumbnailUrl":"http:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2021\/11\/maps-icon-16-300x300.png","datePublished":"2022-09-19T10:47:09+00:00","dateModified":"2024-10-30T10:08:51+00:00","breadcrumb":{"@id":"https:\/\/www.prolococastellanagrotte.it\/8-le-tentazioni-della-badessa-nitti-maria\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.prolococastellanagrotte.it\/8-le-tentazioni-della-badessa-nitti-maria\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.prolococastellanagrotte.it\/8-le-tentazioni-della-badessa-nitti-maria\/#primaryimage","url":"http:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2021\/11\/maps-icon-16-300x300.png","contentUrl":"http:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2021\/11\/maps-icon-16-300x300.png"},{"@type":"BreadcrumbList","@id":"https:\/\/www.prolococastellanagrotte.it\/8-le-tentazioni-della-badessa-nitti-maria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.prolococastellanagrotte.it\/"},{"@type":"ListItem","position":2,"name":"24 &#8211; Badessa &#8211; Tentazioni della badessa"}]},{"@type":"WebSite","@id":"https:\/\/www.prolococastellanagrotte.it\/#website","url":"https:\/\/www.prolococastellanagrotte.it\/","name":"Pro Loco Castellana Grotte | Don Nicola Pellegrino","description":"","publisher":{"@id":"https:\/\/www.prolococastellanagrotte.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.prolococastellanagrotte.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.prolococastellanagrotte.it\/#organization","name":"Pro Loco Castellana Grotte | Don Nicola Pellegrino","url":"https:\/\/www.prolococastellanagrotte.it\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.prolococastellanagrotte.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2021\/11\/cropped-logos_definitivo.png","contentUrl":"https:\/\/www.prolococastellanagrotte.it\/wp-content\/uploads\/2021\/11\/cropped-logos_definitivo.png","width":300,"height":157,"caption":"Pro Loco Castellana Grotte | Don Nicola Pellegrino"},"image":{"@id":"https:\/\/www.prolococastellanagrotte.it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.prolococastellanagrotte.it\/en\/wp-json\/wp\/v2\/pages\/723","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.prolococastellanagrotte.it\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.prolococastellanagrotte.it\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.prolococastellanagrotte.it\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.prolococastellanagrotte.it\/en\/wp-json\/wp\/v2\/comments?post=723"}],"version-history":[{"count":16,"href":"https:\/\/www.prolococastellanagrotte.it\/en\/wp-json\/wp\/v2\/pages\/723\/revisions"}],"predecessor-version":[{"id":2027,"href":"https:\/\/www.prolococastellanagrotte.it\/en\/wp-json\/wp\/v2\/pages\/723\/revisions\/2027"}],"wp:attachment":[{"href":"https:\/\/www.prolococastellanagrotte.it\/en\/wp-json\/wp\/v2\/media?parent=723"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}